{"id":14742,"date":"2023-05-12T15:10:11","date_gmt":"2023-05-12T19:10:11","guid":{"rendered":"https:\/\/www.oacas.org\/2023\/05\/la-journee-des-enfants-et-des-jeunes-pris-en-charge-est-commemoree-a-travers-une-journee-de-sensibilisation-et-une-reception-queens-park\/"},"modified":"2023-05-12T15:33:25","modified_gmt":"2023-05-12T19:33:25","slug":"la-journee-des-enfants-et-des-jeunes-pris-en-charge-est-commemoree-a-travers-une-journee-de-sensibilisation-et-une-reception-queens-park","status":"publish","type":"post","link":"https:\/\/www.oacas.org\/fr\/2023\/05\/la-journee-des-enfants-et-des-jeunes-pris-en-charge-est-commemoree-a-travers-une-journee-de-sensibilisation-et-une-reception-queens-park\/","title":{"rendered":"La Journ\u00e9e des enfants et des jeunes pris en charge est comm\u00e9mor\u00e9e \u00e0 travers une journ\u00e9e de sensibilisation et une r\u00e9ception Queen&rsquo;s Park"},"content":{"rendered":"<p>Le 14 mai est la Journ\u00e9e des enfants et des jeunes pris en charge, une journ\u00e9e organis\u00e9e par et pour les jeunes pris en charge afin d&rsquo;honorer leurs r\u00e9alisations, leurs points forts et leurs histoires.<\/p>\n<p>Le 9 mai, aux c\u00f4t\u00e9s de <a href=\"https:\/\/www.oacas.org\/fr\/?p=14688\">jeunes ayant une exp\u00e9rience v\u00e9cue dans le syst\u00e8me de protection de l&rsquo;enfance de l&rsquo;Ontario, l&rsquo;AOSAE et la Fondation d&rsquo;aide \u00e0 l&rsquo;enfance du Canada se sont rendus \u00e0 Queen&rsquo;s Park<\/a> dans le cadre de la <a href=\"https:\/\/www.oacas.org\/fr\/publications-et-campagnes\/le-jour-des-enfants-et-des-jeunes-pris-en-charge\/\">campagne #ForgetMeNot<\/a> pour poser la question: \u00cates-vous l\u00e0 pour les enfants pris en charge? Nous avons rencontr\u00e9 plusieurs d\u00e9put\u00e9s provinciaux et le ministre Parsa pour discuter de l&rsquo;am\u00e9lioration du soutien aux jeunes dans les domaines de la sant\u00e9 mentale, du logement, de l&rsquo;\u00e9ducation et de l&#8217;emploi. Plus pr\u00e9cis\u00e9ment, nous avons exhort\u00e9 le gouvernement de l&rsquo;Ontario \u00e0 :<\/p>\n<ul>\n<li>\u00c9largir les services de sant\u00e9 mentale pour les enfants et les jeunes pris en charge gr\u00e2ce \u00e0 des investissements suppl\u00e9mentaires dans la Feuille de route pour le mieux-\u00eatre, y compris les enfants et les jeunes ayant des besoins graves ou complexes en mati\u00e8re de sant\u00e9 mentale.<\/li>\n<li>Veiller \u00e0 ce que les jeunes pris en charge aient acc\u00e8s \u00e0 un logement s\u00e9curitaire, appropri\u00e9 et s\u00e9curis\u00e9 en investissant davantage dans le programme de pr\u00e9vention du sans-abrisme.<\/li>\n<li>Aider les jeunes pris en charge \u00e0 entrer sur le march\u00e9 du travail et \u00e0 s&rsquo;y \u00e9panouir en r\u00e9alisant des investissements cibl\u00e9s sur la reprise de l&rsquo;apprentissage et le d\u00e9veloppement des comp\u00e9tences.<\/li>\n<\/ul>\n<p>Ces <a href=\"http:\/\/www.oacas.org\/wp-content\/uploads\/2023\/05\/Draft_One_Pager_CYICD_Final_5_FR.pdf\">domaines prioritaires<\/a> ont \u00e9t\u00e9 d\u00e9finis \u00e0 la suite d&rsquo;une s\u00e9rie de tables rondes d&rsquo;\u00e9coute organis\u00e9es ce printemps, au cours desquelles nous avons demand\u00e9 \u00e0 des jeunes pris en charge ou ayant \u00e9t\u00e9 pris en charge dans tout l&rsquo;Ontario quels \u00e9taient les d\u00e9fis auxquels ils \u00e9taient confront\u00e9s et quels \u00e9taient les soutiens suppl\u00e9mentaires dont ils avaient besoin pour r\u00e9ussir. Lors de rencontres directes avec les d\u00e9put\u00e9s, nous avons exhort\u00e9 la province \u00e0 reconna\u00eetre que les enfants et les jeunes pris en charge ont des besoins uniques et qu&rsquo;ils ont donc besoin de politiques, de programmes et d&rsquo;investissements sp\u00e9cifiquement adapt\u00e9s.<\/p>\n<p>L&rsquo;AOSAE et la Fondation d&rsquo;aide \u00e0 l&rsquo;enfance du Canada ont \u00e9galement organis\u00e9 une r\u00e9ception \u00e0 Queen&rsquo;s Park pour r\u00e9unir des d\u00e9put\u00e9s, des partenaires communautaires, des organismes de protection de l&rsquo;enfance et des jeunes pris en charge afin de souligner les r\u00e9alisations et la r\u00e9silience des enfants et des jeunes pris en charge et d&rsquo;attirer \u00e0 nouveau l&rsquo;attention sur leurs besoins sp\u00e9cifiques. Au cours de la r\u00e9ception, l&rsquo;AOSAE et la Fondation d&rsquo;aide \u00e0 l&rsquo;enfance du Canada ont soulign\u00e9 la n\u00e9cessit\u00e9 d&rsquo;\u00e9couter les enfants et les jeunes et de centrer leur voix sur le travail que nous accomplissons pour atteindre le m\u00eame objectif collectif : am\u00e9liorer les r\u00e9sultats pour tous les enfants, les jeunes et les familles de l&rsquo;Ontario.<\/p>\n<p>Des d\u00e9put\u00e9s de tout le gouvernement, dont l&rsquo;honorable Michael Parsa, ministre des Enfants, de la Communaut\u00e9 et des Services sociaux, les d\u00e9put\u00e9s Mike Schreiner, John Fraser et Taylor, y ont particip\u00e9 et ont r\u00e9fl\u00e9chi \u00e0 la r\u00e9silience des enfants et des jeunes pris en charge et \u00e0 la n\u00e9cessit\u00e9 de prendre des mesures pour s&rsquo;assurer qu&rsquo;ils ont acc\u00e8s aux services de soutien dont ils ont besoin pour s&rsquo;\u00e9panouir. Les partenaires communautaires pr\u00e9sents \u00e9taient l&rsquo;<a href=\"https:\/\/ancfsao.ca\/\">Association of Native Child and Family Services Agencies of Ontario<\/a>, le <a href=\"https:\/\/www.ontario.ca\/fr\/page\/bureau-de-lavocat-des-enfants\">Bureau de l&rsquo;avocat des enfants<\/a> et <a href=\"https:\/\/www.stepstonesforyouth.com\/\">StepStones<\/a>.<\/p>\n<p>Les jeunes ayant une exp\u00e9rience v\u00e9cue de la protection de l&rsquo;enfance, pr\u00e9sent\u00e9s dans la <a href=\"https:\/\/www.oacas.org\/fr\/publications-et-campagnes\/le-jour-des-enfants-et-des-jeunes-pris-en-charge\/\">campagne #ForgetMeNot<\/a>, \u00e9taient \u00e9galement pr\u00e9sents, et certains ont fait des remarques \u00e9mouvantes et sinc\u00e8res et ont partag\u00e9 leurs talents avec la salle, nous rappelant qu&rsquo;ils ne peuvent pas \u00eatre oubli\u00e9s. Les r\u00e9cits de <a href=\"http:\/\/myvanloc.com\/\">Van<\/a>, <a href=\"https:\/\/www.rosejonesmusic.com\/\">Rose<\/a>, Samuel, Kaygan, Byanka, Troy et Aidan ont centr\u00e9 l&rsquo;\u00e9v\u00e9nement dans ce qui compte le plus : la s\u00e9curit\u00e9, le bien-\u00eatre et la r\u00e9ussite des enfants et des jeunes pris en charge. Il s&rsquo;agit d&rsquo;une responsabilit\u00e9 partag\u00e9e qui implique que les communaut\u00e9s, les familles, les syst\u00e8mes intersect\u00e9s, les acteurs communautaires et le gouvernement travaillent ensemble pour \u00eatre l\u00e0 pour les enfants pris en charge.<\/p>\n<p>D\u00e9couvrez comment vous pouvez rejoindre la campagne #ForgetMeNot sur <a href=\"https:\/\/www.oacas.org\/fr\/publications-et-campagnes\/le-jour-des-enfants-et-des-jeunes-pris-en-charge\/\">oacas.org\/forgetmenot<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":21,"featured_media":14706,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[43,34,42,95,61,46,33,41],"tags":[],"class_list":["post-14742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agences-daide-a-lenfance","category-en-vedette","category-enfants","category-evenements","category-gouvernement","category-jeunes","category-partenaires-communautaires","category-representation"],"_links":{"self":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/posts\/14742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/comments?post=14742"}],"version-history":[{"count":0,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/posts\/14742\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/media\/14706"}],"wp:attachment":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/media?parent=14742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/categories?post=14742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/tags?post=14742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}