{"id":6127,"date":"2019-08-09T12:22:53","date_gmt":"2019-08-09T16:22:53","guid":{"rendered":"http:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1.jpg"},"modified":"2019-08-09T12:22:53","modified_gmt":"2019-08-09T16:22:53","slug":"dresspurple2019-poster5","status":"inherit","type":"attachment","link":"https:\/\/www.oacas.org\/fr\/dresspurple2019-poster5\/","title":{"rendered":"dresspurple2019-poster5"},"author":21,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_links_to":"","_links_to_target":""},"class_list":["post-6127","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a rel='wp-prettyPhoto' href='https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1.jpg' rel=\"wp-prettyPhoto[6127]\"><img fetchpriority=\"high\" decoding=\"async\" width=\"194\" height=\"300\" src=\"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-194x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-194x300.jpg 194w, https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-768x1187.jpg 768w, https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-663x1024.jpg 663w, https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1.jpg 792w\" sizes=\"(max-width: 194px) 100vw, 194px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":792,"height":1224,"file":"2019\/08\/dresspurple2019-poster5-1.jpg","sizes":{"thumbnail":{"file":"dresspurple2019-poster5-1-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-150x150.jpg"},"medium":{"file":"dresspurple2019-poster5-1-194x300.jpg","width":194,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-194x300.jpg"},"medium_large":{"file":"dresspurple2019-poster5-1-768x1187.jpg","width":768,"height":1187,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-768x1187.jpg"},"large":{"file":"dresspurple2019-poster5-1-663x1024.jpg","width":663,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-663x1024.jpg"},"timeline-express":{"file":"dresspurple2019-poster5-1-350x120.jpg","width":350,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-350x120.jpg"},"timeline-express-thumbnail":{"file":"dresspurple2019-poster5-1-200x120.jpg","width":200,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-200x120.jpg"},"sow-carousel-default":{"file":"dresspurple2019-poster5-1-272x182.jpg","width":272,"height":182,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1-272x182.jpg"},"full":{"file":"dresspurple2019-poster5-1.jpg","width":792,"height":1224,"mime_type":"image\/jpeg","source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.oacas.org\/wp-content\/uploads\/2019\/08\/dresspurple2019-poster5-1.jpg","filename":"dresspurple2019-poster5-1.jpg","filesize":null,"_links":{"self":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/media\/6127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oacas.org\/fr\/wp-json\/wp\/v2\/comments?post=6127"}]}}